{"id":6289,"date":"2025-04-09T22:46:56","date_gmt":"2025-04-09T22:46:56","guid":{"rendered":"https:\/\/sihay.com.mx\/basededatos\/?post_type=product&#038;p=6289"},"modified":"2025-04-09T22:47:53","modified_gmt":"2025-04-09T22:47:53","slug":"6289","status":"publish","type":"product","link":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/","title":{"rendered":"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-sm\">\n\t\t<strong>C\u00f3digo:<\/strong> <strong class=\"text-danger\"> ANFL-M4<\/strong>\n    <\/div>\n<div class=\"col-sm\">\n\t<strong>N\u00famero de registros: <\/strong>500\n\t<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm \">\n\t<strong>Folio: <\/strong><span class=\"text-danger\"> AF0425B0004<\/span>\n\t<\/div>\n<\/div>\n<p><strong>Segmentaci\u00f3n:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">\n\tPersonas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional.<\/div>\n<\/div>\n<p><strong>Campos Contenidos:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">\n\tNombre \/ Celular \/ Email.  <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm\">\n\t<strong>Garant\u00eda: <\/strong>80%-85% <strong>Precio Original: <\/strong><del>$3,967.00<\/del> <strong>Descuento Especial: <\/strong><strong class=\"text-danger\">20%<\/strong>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col text-center\">\n\t<strong>Total a Pagar: <\/strong><strong class=\"text-danger\">$3,173.00<\/strong>\n\t<\/div>\n<\/div>\n","protected":false},"featured_media":1891,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[159],"product_tag":[269,582,234,206,235,216,204,207,205,183,181,417,418,277,275,272,270,584,274,266,278,280,587,267,589,590,366,279,356,324,323,550,321,307,570,416,304],"class_list":{"0":"post-6289","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-personas","7":"product_tag-b2b-database-for-marketing","8":"product_tag-b2b-email-lists","9":"product_tag-base-de-datos","10":"product_tag-base-de-datos-correo-electronico","11":"product_tag-base-de-datos-correos-electronicos","12":"product_tag-base-de-datos-de-correos","13":"product_tag-base-de-datos-de-emails","14":"product_tag-base-de-datos-de-telefonos","15":"product_tag-base-de-datos-email","16":"product_tag-base-de-datos-email-marketing","17":"product_tag-base-de-datos-emails","18":"product_tag-base-de-datos-telefono","19":"product_tag-bases-de-datos-de-telefonos-fijos","20":"product_tag-buy-email-address","21":"product_tag-buy-email-address-database","22":"product_tag-database","23":"product_tag-database-of-email-advertising","24":"product_tag-database-of-emails","25":"product_tag-email-address-database","26":"product_tag-email-database","27":"product_tag-email-database-for-sale","28":"product_tag-email-list-providers","29":"product_tag-email-lists","30":"product_tag-email-marketer","31":"product_tag-email-marketing-list","32":"product_tag-email-services-marketing","33":"product_tag-emailing","34":"product_tag-emails-for-sale","35":"product_tag-lista","36":"product_tag-lista-de-correo-electronico","37":"product_tag-lista-de-email","38":"product_tag-lista-de-numeros-de-telefonos","39":"product_tag-listado-de-emails","40":"product_tag-phone-number-database","41":"product_tag-phone-number-list","42":"product_tag-telefono","43":"product_tag-telephone-number","45":"first","46":"instock","47":"sale","48":"virtual","49":"purchasable","50":"product-type-simple"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"C\u00f3digo: ANFL-M4 N\u00famero de registros: 500 Folio: AF0425B0004 Segmentaci\u00f3n: Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional. Campos Contenidos: Nombre \/ Celular \/ Email. Garant\u00eda: 80%-85% Precio Original: $3,967.00 Descuento Especial: 20% Total a Pagar: $3,173.00\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"eShop\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional - eShop\" \/>\n\t\t<meta property=\"og:description\" content=\"C\u00f3digo: ANFL-M4 N\u00famero de registros: 500 Folio: AF0425B0004 Segmentaci\u00f3n: Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional. Campos Contenidos: Nombre \/ Celular \/ Email. Garant\u00eda: 80%-85% Precio Original: $3,967.00 Descuento Especial: 20% Total a Pagar: $3,173.00\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-04-09T22:46:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-04-09T22:47:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional - eShop\" \/>\n\t\t<meta name=\"twitter:description\" content=\"C\u00f3digo: ANFL-M4 N\u00famero de registros: 500 Folio: AF0425B0004 Segmentaci\u00f3n: Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional. Campos Contenidos: Nombre \/ Celular \/ Email. Garant\u00eda: 80%-85% Precio Original: $3,967.00 Descuento Especial: 20% Total a Pagar: $3,173.00\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/#listItem\",\"name\":\"Personas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/#listItem\",\"position\":3,\"name\":\"Personas\",\"item\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#listItem\",\"name\":\"Personas f\\u00edsicas, de 18 a 73 a\\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\\u00e9dito a Nivel Nacional\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#listItem\",\"position\":4,\"name\":\"Personas f\\u00edsicas, de 18 a 73 a\\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\\u00e9dito a Nivel Nacional\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/#listItem\",\"name\":\"Personas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/#organization\",\"name\":\"eShop\",\"description\":\"Compra venta de base de datos en todo M\\u00e9xico y Latinoam\\u00e9rica. Email marketing mexico. Base de datos emails, emailing, mailing.\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/\",\"telephone\":\"+523334686254\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-eP.png\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#organizationLogo\",\"width\":250,\"height\":94,\"caption\":\"logo-ePublicidad\"},\"image\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#webpage\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/\",\"name\":\"Personas f\\u00edsicas, de 18 a 73 a\\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\\u00e9dito a Nivel Nacional - eShop\",\"description\":\"C\\u00f3digo: ANFL-M4 N\\u00famero de registros: 500 Folio: AF0425B0004 Segmentaci\\u00f3n: Personas f\\u00edsicas, de 18 a 73 a\\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\\u00e9dito a Nivel Nacional. Campos Contenidos: Nombre \\\/ Celular \\\/ Email. Garant\\u00eda: 80%-85% Precio Original: $3,967.00 Descuento Especial: 20% Total a Pagar: $3,173.00\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/paquetes-personas-segmentadas.png\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#mainImage\",\"width\":748,\"height\":800,\"caption\":\"Base de datos de personas \\\/ People database\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/6289\\\/#mainImage\"},\"datePublished\":\"2025-04-09T22:46:56+00:00\",\"dateModified\":\"2025-04-09T22:47:53+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/#website\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/\",\"name\":\"eShop\",\"description\":\"Compra venta de base de datos en todo M\\u00e9xico y Latinoam\\u00e9rica. Email marketing mexico. Base de datos emails, emailing, mailing.\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional - eShop","description":"C\u00f3digo: ANFL-M4 N\u00famero de registros: 500 Folio: AF0425B0004 Segmentaci\u00f3n: Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional. Campos Contenidos: Nombre \/ Celular \/ Email. Garant\u00eda: 80%-85% Precio Original: $3,967.00 Descuento Especial: 20% Total a Pagar: $3,173.00","canonical_url":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos#listItem","position":1,"name":"Inicio","item":"https:\/\/sihay.com.mx\/basededatos","nextItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/#listItem","position":2,"name":"Tienda","item":"https:\/\/sihay.com.mx\/basededatos\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/#listItem","name":"Personas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/#listItem","position":3,"name":"Personas","item":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#listItem","name":"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#listItem","position":4,"name":"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional","previousItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/#listItem","name":"Personas"}}]},{"@type":"Organization","@id":"https:\/\/sihay.com.mx\/basededatos\/#organization","name":"eShop","description":"Compra venta de base de datos en todo M\u00e9xico y Latinoam\u00e9rica. Email marketing mexico. Base de datos emails, emailing, mailing.","url":"https:\/\/sihay.com.mx\/basededatos\/","telephone":"+523334686254","logo":{"@type":"ImageObject","url":"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/logo-eP.png","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#organizationLogo","width":250,"height":94,"caption":"logo-ePublicidad"},"image":{"@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#webpage","url":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/","name":"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional - eShop","description":"C\u00f3digo: ANFL-M4 N\u00famero de registros: 500 Folio: AF0425B0004 Segmentaci\u00f3n: Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional. Campos Contenidos: Nombre \/ Celular \/ Email. Garant\u00eda: 80%-85% Precio Original: $3,967.00 Descuento Especial: 20% Total a Pagar: $3,173.00","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/sihay.com.mx\/basededatos\/#website"},"breadcrumb":{"@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#mainImage","width":748,"height":800,"caption":"Base de datos de personas \/ People database"},"primaryImageOfPage":{"@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/#mainImage"},"datePublished":"2025-04-09T22:46:56+00:00","dateModified":"2025-04-09T22:47:53+00:00"},{"@type":"WebSite","@id":"https:\/\/sihay.com.mx\/basededatos\/#website","url":"https:\/\/sihay.com.mx\/basededatos\/","name":"eShop","description":"Compra venta de base de datos en todo M\u00e9xico y Latinoam\u00e9rica. Email marketing mexico. Base de datos emails, emailing, mailing.","inLanguage":"es-MX","publisher":{"@id":"https:\/\/sihay.com.mx\/basededatos\/#organization"}}]},"og:locale":"es_MX","og:site_name":"eShop","og:type":"article","og:title":"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional - eShop","og:description":"C\u00f3digo: ANFL-M4 N\u00famero de registros: 500 Folio: AF0425B0004 Segmentaci\u00f3n: Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional. Campos Contenidos: Nombre \/ Celular \/ Email. Garant\u00eda: 80%-85% Precio Original: $3,967.00 Descuento Especial: 20% Total a Pagar: $3,173.00","og:url":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/","article:published_time":"2025-04-09T22:46:56+00:00","article:modified_time":"2025-04-09T22:47:53+00:00","twitter:card":"summary_large_image","twitter:title":"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional - eShop","twitter:description":"C\u00f3digo: ANFL-M4 N\u00famero de registros: 500 Folio: AF0425B0004 Segmentaci\u00f3n: Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional. Campos Contenidos: Nombre \/ Celular \/ Email. Garant\u00eda: 80%-85% Precio Original: $3,967.00 Descuento Especial: 20% Total a Pagar: $3,173.00"},"aioseo_meta_data":{"post_id":"6289","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-04-09 22:47:05","updated":"2025-06-23 20:34:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sihay.com.mx\/basededatos\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sihay.com.mx\/basededatos\/tienda\/\" title=\"Tienda\">Tienda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/\" title=\"Personas\">Personas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPersonas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/sihay.com.mx\/basededatos"},{"label":"Tienda","link":"https:\/\/sihay.com.mx\/basededatos\/tienda\/"},{"label":"Personas","link":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/"},{"label":"Personas f\u00edsicas, de 18 a 73 a\u00f1os de edad, con ingresos mayores a $20,000 mensuales que sean tarjetahabientes de al menos una tarjeta de cr\u00e9dito a Nivel Nacional","link":"https:\/\/sihay.com.mx\/basededatos\/tienda\/6289\/"}],"_links":{"self":[{"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product\/6289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/comments?post=6289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/media\/1891"}],"wp:attachment":[{"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/media?parent=6289"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product_brand?post=6289"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product_cat?post=6289"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product_tag?post=6289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}