{"id":5062,"date":"2022-11-16T21:32:57","date_gmt":"2022-11-16T21:32:57","guid":{"rendered":"https:\/\/sihay.com.mx\/basededatos\/shop-2\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/"},"modified":"2023-02-21T21:50:16","modified_gmt":"2023-02-21T21:50:16","slug":"consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico","status":"publish","type":"product","link":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/","title":{"rendered":"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>C\u00f3digo:<\/strong> LAMA-C9-2<\/div>\n<div class=\"col-sm\"><strong>N\u00famero de registros: 600<\/strong><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm \"><strong>Folio: <\/strong><span class=\"text-danger\"><strong>\u00a0<\/strong>SME-0716-AN-2<\/span><\/div>\n<\/div>\n<p><strong>Segmentaci\u00f3n:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico.<\/div>\n<\/div>\n<p><strong>Campos Contenidos:<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-sm \">Nombre \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Tel\u00e9fono fijo\/ Email.<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-sm\"><strong>Garant\u00eda: <\/strong>80%-85% <strong>Precio Original: <\/strong><del>$5,580.00<\/del> <strong>Descuento Especial: <\/strong><strong class=\"text-danger\">20%<\/strong><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col text-center\"><strong>Total a Pagar: <\/strong><strong class=\"text-danger\">$4,464.00<\/strong><\/div>\n<\/div>\n","protected":false},"featured_media":1891,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[166,159],"product_tag":[269,234,229,206,235,216,204,237,205,183,181,185,240,238,277,275,358,272,270,274,266,278,280,267,279,324,323,321,322,305,347,359,303],"class_list":{"0":"post-5062","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-en-mexico","7":"product_cat-personas","8":"product_tag-b2b-database-for-marketing","9":"product_tag-base-de-datos","10":"product_tag-base-de-datos-cdmx","11":"product_tag-base-de-datos-correo-electronico","12":"product_tag-base-de-datos-correos-electronicos","13":"product_tag-base-de-datos-de-correos","14":"product_tag-base-de-datos-de-emails","15":"product_tag-base-de-datos-de-personas","16":"product_tag-base-de-datos-email","17":"product_tag-base-de-datos-email-marketing","18":"product_tag-base-de-datos-emails","19":"product_tag-base-de-datos-personalizadas","20":"product_tag-base-de-datos-personas","21":"product_tag-base-de-datos-personas-latinoamerica","22":"product_tag-buy-email-address","23":"product_tag-buy-email-address-database","24":"product_tag-consumer-database","25":"product_tag-database","26":"product_tag-database-of-email-advertising","27":"product_tag-email-address-database","28":"product_tag-email-database","29":"product_tag-email-database-for-sale","30":"product_tag-email-list-providers","31":"product_tag-email-marketer","32":"product_tag-emails-for-sale","33":"product_tag-lista-de-correo-electronico","34":"product_tag-lista-de-email","35":"product_tag-listado-de-emails","36":"product_tag-listado-de-emails-de-empresas","37":"product_tag-numbers-database","38":"product_tag-personas-en-cdmx","39":"product_tag-personas-fisicas","40":"product_tag-phone-database","42":"first","43":"instock","44":"shipping-taxable","45":"product-type-simple"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"C\u00f3digo: LAMA-C9-2 N\u00famero de registros: 600 Folio: SME-0716-AN-2 Segmentaci\u00f3n: Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. Campos Contenidos: Nombre \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Tel\u00e9fono fijo\/ Email. Garant\u00eda: 80%-85% Precio Original: $5,580.00 Descuento Especial: 20% Total a Pagar: $4,464.00\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"eShop\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. - eShop\" \/>\n\t\t<meta property=\"og:description\" content=\"C\u00f3digo: LAMA-C9-2 N\u00famero de registros: 600 Folio: SME-0716-AN-2 Segmentaci\u00f3n: Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. Campos Contenidos: Nombre \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Tel\u00e9fono fijo\/ Email. Garant\u00eda: 80%-85% Precio Original: $5,580.00 Descuento Especial: 20% Total a Pagar: $4,464.00\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"748\" \/>\n\t\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-11-16T21:32:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-02-21T21:50:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. - eShop\" \/>\n\t\t<meta name=\"twitter:description\" content=\"C\u00f3digo: LAMA-C9-2 N\u00famero de registros: 600 Folio: SME-0716-AN-2 Segmentaci\u00f3n: Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. Campos Contenidos: Nombre \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Tel\u00e9fono fijo\/ Email. Garant\u00eda: 80%-85% Precio Original: $5,580.00 Descuento Especial: 20% Total a Pagar: $4,464.00\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/#listItem\",\"name\":\"Personas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/#listItem\",\"position\":3,\"name\":\"Personas\",\"item\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/en-mexico\\\/#listItem\",\"name\":\"En M\\u00e9xico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/en-mexico\\\/#listItem\",\"position\":4,\"name\":\"En M\\u00e9xico\",\"item\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/en-mexico\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#listItem\",\"name\":\"Consumidores de cursos de panader\\u00eda y reposter\\u00eda en la zona metropolitana del valle de M\\u00e9xico.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/#listItem\",\"name\":\"Personas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#listItem\",\"position\":5,\"name\":\"Consumidores de cursos de panader\\u00eda y reposter\\u00eda en la zona metropolitana del valle de M\\u00e9xico.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/product-category\\\/personas\\\/en-mexico\\\/#listItem\",\"name\":\"En M\\u00e9xico\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/#organization\",\"name\":\"eShop\",\"description\":\"Compra venta de base de datos en todo M\\u00e9xico y Latinoam\\u00e9rica. Email marketing mexico. Base de datos emails, emailing, mailing.\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/\",\"telephone\":\"+523334686254\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo-eP.png\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#organizationLogo\",\"width\":250,\"height\":94,\"caption\":\"logo-ePublicidad\"},\"image\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#webpage\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/\",\"name\":\"Consumidores de cursos de panader\\u00eda y reposter\\u00eda en la zona metropolitana del valle de M\\u00e9xico. - eShop\",\"description\":\"C\\u00f3digo: LAMA-C9-2 N\\u00famero de registros: 600 Folio: SME-0716-AN-2 Segmentaci\\u00f3n: Consumidores de cursos de panader\\u00eda y reposter\\u00eda en la zona metropolitana del valle de M\\u00e9xico. Campos Contenidos: Nombre \\\/ Direcci\\u00f3n \\\/ Ciudad \\\/ Estado \\\/ Tel\\u00e9fono fijo\\\/ Email. Garant\\u00eda: 80%-85% Precio Original: $5,580.00 Descuento Especial: 20% Total a Pagar: $4,464.00\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/paquetes-personas-segmentadas.png\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#mainImage\",\"width\":748,\"height\":800,\"caption\":\"Base de datos de personas \\\/ People database\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/tienda\\\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\\\/#mainImage\"},\"datePublished\":\"2022-11-16T21:32:57+00:00\",\"dateModified\":\"2023-02-21T21:50:16+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/#website\",\"url\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/\",\"name\":\"eShop\",\"description\":\"Compra venta de base de datos en todo M\\u00e9xico y Latinoam\\u00e9rica. Email marketing mexico. Base de datos emails, emailing, mailing.\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/sihay.com.mx\\\/basededatos\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. - eShop","description":"C\u00f3digo: LAMA-C9-2 N\u00famero de registros: 600 Folio: SME-0716-AN-2 Segmentaci\u00f3n: Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. Campos Contenidos: Nombre \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Tel\u00e9fono fijo\/ Email. Garant\u00eda: 80%-85% Precio Original: $5,580.00 Descuento Especial: 20% Total a Pagar: $4,464.00","canonical_url":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos#listItem","position":1,"name":"Inicio","item":"https:\/\/sihay.com.mx\/basededatos","nextItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/#listItem","position":2,"name":"Tienda","item":"https:\/\/sihay.com.mx\/basededatos\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/#listItem","name":"Personas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/#listItem","position":3,"name":"Personas","item":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/en-mexico\/#listItem","name":"En M\u00e9xico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/en-mexico\/#listItem","position":4,"name":"En M\u00e9xico","item":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/en-mexico\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#listItem","name":"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico."},"previousItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/#listItem","name":"Personas"}},{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#listItem","position":5,"name":"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico.","previousItem":{"@type":"ListItem","@id":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/en-mexico\/#listItem","name":"En M\u00e9xico"}}]},{"@type":"Organization","@id":"https:\/\/sihay.com.mx\/basededatos\/#organization","name":"eShop","description":"Compra venta de base de datos en todo M\u00e9xico y Latinoam\u00e9rica. Email marketing mexico. Base de datos emails, emailing, mailing.","url":"https:\/\/sihay.com.mx\/basededatos\/","telephone":"+523334686254","logo":{"@type":"ImageObject","url":"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/logo-eP.png","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#organizationLogo","width":250,"height":94,"caption":"logo-ePublicidad"},"image":{"@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#webpage","url":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/","name":"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. - eShop","description":"C\u00f3digo: LAMA-C9-2 N\u00famero de registros: 600 Folio: SME-0716-AN-2 Segmentaci\u00f3n: Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. Campos Contenidos: Nombre \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Tel\u00e9fono fijo\/ Email. Garant\u00eda: 80%-85% Precio Original: $5,580.00 Descuento Especial: 20% Total a Pagar: $4,464.00","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/sihay.com.mx\/basededatos\/#website"},"breadcrumb":{"@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png","@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#mainImage","width":748,"height":800,"caption":"Base de datos de personas \/ People database"},"primaryImageOfPage":{"@id":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/#mainImage"},"datePublished":"2022-11-16T21:32:57+00:00","dateModified":"2023-02-21T21:50:16+00:00"},{"@type":"WebSite","@id":"https:\/\/sihay.com.mx\/basededatos\/#website","url":"https:\/\/sihay.com.mx\/basededatos\/","name":"eShop","description":"Compra venta de base de datos en todo M\u00e9xico y Latinoam\u00e9rica. Email marketing mexico. Base de datos emails, emailing, mailing.","inLanguage":"es-MX","publisher":{"@id":"https:\/\/sihay.com.mx\/basededatos\/#organization"}}]},"og:locale":"es_MX","og:site_name":"eShop","og:type":"article","og:title":"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. - eShop","og:description":"C\u00f3digo: LAMA-C9-2 N\u00famero de registros: 600 Folio: SME-0716-AN-2 Segmentaci\u00f3n: Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. Campos Contenidos: Nombre \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Tel\u00e9fono fijo\/ Email. Garant\u00eda: 80%-85% Precio Original: $5,580.00 Descuento Especial: 20% Total a Pagar: $4,464.00","og:url":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/","og:image":"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png","og:image:secure_url":"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png","og:image:width":"748","og:image:height":"800","article:published_time":"2022-11-16T21:32:57+00:00","article:modified_time":"2023-02-21T21:50:16+00:00","twitter:card":"summary_large_image","twitter:title":"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. - eShop","twitter:description":"C\u00f3digo: LAMA-C9-2 N\u00famero de registros: 600 Folio: SME-0716-AN-2 Segmentaci\u00f3n: Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico. Campos Contenidos: Nombre \/ Direcci\u00f3n \/ Ciudad \/ Estado \/ Tel\u00e9fono fijo\/ Email. Garant\u00eda: 80%-85% Precio Original: $5,580.00 Descuento Especial: 20% Total a Pagar: $4,464.00","twitter:image":"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png"},"aioseo_meta_data":{"post_id":"5062","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"featured","og_image_url":"https:\/\/sihay.com.mx\/basededatos\/wp-content\/uploads\/2022\/10\/paquetes-personas-segmentadas.png","og_image_width":"748","og_image_height":"800","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-02-09 18:36:32","updated":"2025-06-23 20:17:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sihay.com.mx\/basededatos\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sihay.com.mx\/basededatos\/tienda\/\" title=\"Tienda\">Tienda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/\" title=\"Personas\">Personas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/en-mexico\/\" title=\"En M\u00e9xico\">En M\u00e9xico<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tConsumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/sihay.com.mx\/basededatos"},{"label":"Tienda","link":"https:\/\/sihay.com.mx\/basededatos\/tienda\/"},{"label":"Personas","link":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/"},{"label":"En M\u00e9xico","link":"https:\/\/sihay.com.mx\/basededatos\/product-category\/personas\/en-mexico\/"},{"label":"Consumidores de cursos de panader\u00eda y reposter\u00eda en la zona metropolitana del valle de M\u00e9xico.","link":"https:\/\/sihay.com.mx\/basededatos\/tienda\/consumidores-de-cursos-de-panaderia-y-reposteria-en-la-zona-metropolitana-del-valle-de-mexico\/"}],"_links":{"self":[{"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product\/5062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/comments?post=5062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/media\/1891"}],"wp:attachment":[{"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/media?parent=5062"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product_brand?post=5062"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product_cat?post=5062"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sihay.com.mx\/basededatos\/wp-json\/wp\/v2\/product_tag?post=5062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}